{"id":1476,"date":"2024-07-22T12:08:12","date_gmt":"2024-07-22T10:08:12","guid":{"rendered":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/?p=1476"},"modified":"2024-07-22T14:58:20","modified_gmt":"2024-07-22T12:58:20","slug":"pause-estivale","status":"publish","type":"post","link":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/2024\/07\/22\/pause-estivale\/","title":{"rendered":"Pause estivale"},"content":{"rendered":"\n<p>C&rsquo;est la pause estivale pour nos cordes vocales. La reprise aura lieu le lundi 09 septembre 2024 \u00e0 20h30 \u00e0 la salle de la musique.<\/p>\n\n\n\n<p>Nous serons pr\u00e9sents au forum des associations qui se tiendra \u00e0 la salle du Vallon \u00e0 Landivisiau le 07 septembre 2024 de 09h00 \u00e0 15h00. A l&rsquo;\u00e9coute de vos questions et pour accueillir vos inscriptions (possibilit\u00e9 de deux s\u00e9ances d&rsquo;essai avant l&rsquo;inscription d\u00e9finitive).<\/p>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>C&rsquo;est la pause estivale pour nos cordes vocales. La reprise aura lieu le lundi 09 septembre 2024 \u00e0 20h30 \u00e0 la salle de la musique. Nous serons pr\u00e9sents au forum des associations qui se tiendra \u00e0 la salle du Vallon &hellip; <a href=\"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/2024\/07\/22\/pause-estivale\/\">Continuer la lecture <span class=\"meta-nav\">&rarr;<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"h5ap_radio_sources":[],"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1476","post","type-post","status-publish","format-standard","hentry","category-non-classe"],"_links":{"self":[{"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1476","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/comments?post=1476"}],"version-history":[{"count":2,"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1476\/revisions"}],"predecessor-version":[{"id":1483,"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/posts\/1476\/revisions\/1483"}],"wp:attachment":[{"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/media?parent=1476"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/categories?post=1476"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.chorale-yadlavoix-landivisiau.fr\/wordpress\/wp-json\/wp\/v2\/tags?post=1476"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}